{"id":20896,"date":"2018-06-04T00:00:00","date_gmt":"2018-06-03T22:00:00","guid":{"rendered":"https:\/\/myox.fit\/treinamento-forca-colete-eletroestimulacao-muscular\/"},"modified":"2023-12-23T03:42:14","modified_gmt":"2023-12-23T02:42:14","slug":"treinamento-forca-colete-eletroestimulacao-muscular","status":"publish","type":"post","link":"https:\/\/myox.fit\/pt\/treinamento-forca-colete-eletroestimulacao-muscular\/","title":{"rendered":"TREINAMENTO DE FOR\u00c7A COM COLETE DE ELETROESTIMULA\u00c7\u00c3O MUSCULAR"},"content":{"rendered":"<h2><strong>Treinamento de for\u00e7a com trajes ou coletes de eletroestimula\u00e7\u00e3o muscular, que fatores devo considerar?<\/strong><\/h2>\r\n&nbsp;\r\n\r\nO treinamento com a <strong>EMS GLOBAL<\/strong> atrav\u00e9s de <strong>trajes ou coletes de eletroestimula\u00e7\u00e3o muscular <\/strong>se espalhou nos \u00faltimos anos em todo o mundo. Mas os treinadores est\u00e3o aplicando com crit\u00e9rios? Existe um conhecimento real de como a eletroestimula\u00e7\u00e3o deve ser aplicada?\r\n\r\n&nbsp;\r\n\r\nNeste post vamos focar na <strong>aplica\u00e7\u00e3o da EMS Global no treinamento de for\u00e7a <\/strong>e vamos tentar oferecer de um modo simples e pr\u00e1tico \u00a0este crit\u00e9rio que lamentavelmente pensamos que n\u00e3o existe hoje e que isto n\u00e3o s\u00f3 sup\u00f5e um desprest\u00edgio para o profissional e a tecnologia em si, mais se n\u00e3o pior ainda , sup\u00f5e que o cliente n\u00e3o est\u00e1 recebendo um servi\u00e7o de acordo com seus objetivos e tamb\u00e9m est\u00e1 se expondo ao um risco.\r\n\r\n&nbsp;\r\n\r\n<img decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/www.myox.fit\/wp-content\/uploads\/2018\/05\/Thais-ems-global-fuerza-281x300.jpg\" \/>\r\n\r\nO <strong>treinamento de for\u00e7a<\/strong> \u00e9, por muitas raz\u00f5es, o mais procurado em todo o mundo pelos clientes que vai aos centros esportivos, todos n\u00f3s encontramos declara\u00e7\u00f5es familiares como estas:\r\n<ul>\r\n \t<li><em>Eu gostaria de tonificar meu corpo<\/em><\/li>\r\n \t<li><em>Gostaria de endurecer, acho que tenho flacidez<\/em><\/li>\r\n \t<li><em>Eu gostaria de levantar minha bunda e me sentir mais bonita<\/em><\/li>\r\n \t<li><em>Eu quero aumentar o volume dos meus bra\u00e7os e peito<\/em><\/li>\r\n \t<li><em>Eu preciso ganhar for\u00e7a para competir &#8230;<\/em><\/li>\r\n<\/ul>\r\n&nbsp;\r\n\r\nEnt\u00e3o o <strong>personal trainer que trabalha com a eletroestimula\u00e7\u00e3o muscular global<\/strong> deve ter claras duas principais ideias:\r\n<ul>\r\n \t<li>\r\n<h3><span style=\"color: #0000ff;\"><strong>A eletroestimula\u00e7\u00e3o muscular mostrou-se eficaz no ganho de for\u00e7a e massa muscular.<\/strong><\/span><\/h3>\r\n<\/li>\r\n \t<li>\r\n<h3><span style=\"color: #0000ff;\"><strong>A eletroestimula\u00e7\u00e3o muscular \u00e9 um complemento ao treinamento e n\u00e3o a um \u00fanico sistema.<\/strong><\/span><\/h3>\r\n<\/li>\r\n<\/ul>\r\n&nbsp;\r\n\r\nA partir daqui, falamos sobre individualizar o treinamento para os nossos clientes, para faz\u00ea-lo de uma forma pr\u00e1tica e reprodut\u00edvel, vou continuar minha escrita como pontos:\r\n\r\n&nbsp;\r\n<h2><strong>QUAIS SAO OS PAR\u00c2METROS ELETRICOS PARA DETERMINAR OS DIFERENTES OBJETIVOS?<\/strong><\/h2>\r\n<ul>\r\n \t<li><strong>INTENSIDADE (mA):<\/strong> uma vez realizado a adequada progress\u00e3o do treinamento com os <strong>crit\u00e9rios de progress\u00e3o Myox EMS<\/strong> e nos encontramos no ponto ideal para exigir o m\u00e1ximo para o nosso cliente \/ atleta, poderemos administrar a m\u00e1xima energia toler\u00e1vel tendo em conta os diferentes &#8221; supostos m\u00e1ximos &#8220;:<\/li>\r\n \t<li>M\u00e1xima isom\u00e9trica: execu\u00e7\u00f5es sem movimento<\/li>\r\n \t<li>m\u00e1ximo din\u00e2mico: a intensidade aplicada deve permitir uma amplo movimento de articula\u00e7\u00f5es<\/li>\r\n \t<li>m\u00e1ximo t\u00e9cnico: deve permitir execu\u00e7\u00f5es t\u00e9cnicas com qualidade, em nenhum caso o impulso el\u00e9trico estar\u00e1 causando uma deteriora\u00e7\u00e3o t\u00e9cnica.<\/li>\r\n<\/ul>\r\n&nbsp;\r\n\r\nTamb\u00e9m devemos levar em conta dois grandes perfis de clientes:\r\n<ul>\r\n \t<li><strong>Usu\u00e1rio comum que deseja tonificar<\/strong>: n\u00e3o h\u00e1 necessidade de lev\u00e1-lo ao m\u00e1ximo toler\u00e1vel, sim podemos aumentar gradualmente o nosso n\u00edvel de exig\u00eancia, mas n\u00e3o se justifica alcan\u00e7ar a estes m\u00e1ximos.<\/li>\r\n \t<li><strong>Atleta profissional ou atleta exigente<\/strong>: sim, precisaremos atingir esses n\u00edveis de exig\u00eancia m\u00e1xima, obviamente, com planejamento adequado.<\/li>\r\n<\/ul>\r\n<img decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/www.myox.fit\/wp-content\/uploads\/2018\/05\/thais-traje-electroestimulacion-myox-ems-300x226.jpg\" \/>\r\n<ul>\r\n \t<li><strong>CRONAXIA (us):<\/strong> tempo m\u00ednimo de impulso para produzir despolariza\u00e7\u00e3o do nervo motor e consequentemente a contra\u00e7\u00e3o muscular. Tamb\u00e9m chamado tecnicamente de <strong>&#8220;largura de pulso&#8221;<\/strong> porque corresponde \u00e0 largura (dura\u00e7\u00e3o) da <strong>onda el\u00e9trica retangular<\/strong>. O ideal \u00e9 poder respeitar as Cronaxias para as respectivas \u00e1reas musculares:<\/li>\r\n \t<li><strong>ANTEBRAZO: 150 us<\/strong><\/li>\r\n \t<li><strong>BRA\u00c7O: 200 us<\/strong><\/li>\r\n \t<li><strong>TORAX: 250 us<\/strong><\/li>\r\n \t<li><strong>ABDOMEN: 300 us<\/strong><\/li>\r\n \t<li><strong>COXA E GLUTEOS: 350 us<\/strong><\/li>\r\n \t<li><strong>PERNAS: 400 nus<\/strong><\/li>\r\n<\/ul>\r\n&nbsp;\r\n\r\nPara as marcas de <strong>trajes ou coletes de eletroestimula\u00e7\u00e3o<\/strong> que n\u00e3o permitem a personaliza\u00e7\u00e3o da cronaxia por \u00e1reas, recomendamos:\r\n<ul>\r\n \t<li>Comece com o <strong>cronaxias de 150 a 200 us nas primeiras sess\u00f5es<\/strong><\/li>\r\n \t<li>V\u00e1 <strong>aumentando progressivamente<\/strong>, ter em conta que uma cronaxia maior tamb\u00e9m significa um maior recrutamento motor.<\/li>\r\n \t<li>Os <strong>n\u00edveis m\u00e1ximos de for\u00e7a estar\u00e3o entre 300 e 350 us<\/strong>.<\/li>\r\n<\/ul>\r\n&nbsp;\r\n<ul>\r\n \t<li><strong>FREQUENCIA (Hz): <\/strong>n\u00famero de impulsos por segundo, \u00e9 o principal par\u00e2metro el\u00e9trico e determina o objetivo. Em rela\u00e7\u00e3o ao tema espec\u00edfico que nos interessa neste artigo, especificamos os seguintes dados:<\/li>\r\n \t<li><strong>Ganho de t\u00f4nus \u200b\u200bmuscular: 45 a 55 Hz, m\u00e1ximo de 60 Hz<\/strong><\/li>\r\n \t<li><strong>Ganho de massa muscular: 70 a 75 Hz<\/strong><\/li>\r\n \t<li><strong>Ganho de for\u00e7a e resist\u00eancia: 60 a 70 Hz<\/strong><\/li>\r\n \t<li><strong>Ganho de for\u00e7a m\u00e1xima: 80 a 100 Hz<\/strong><\/li>\r\n \t<li><strong>Ganho de Pot\u00eancia: 100 a 120 Hz<\/strong><\/li>\r\n \t<li><strong>Ganho de pot\u00eancia em profissionais: at\u00e9 150 Hz<\/strong><\/li>\r\n<\/ul>\r\n&nbsp;\r\n\r\n<strong>RAMPA:<\/strong> tempo que leva desde do in\u00edcio do impulso \u00e0 sua intensidade m\u00e1xima, desde <strong>Myox<\/strong> recomendamos trabalhar de forma sensata, rampas \u00e9 um dos par\u00e2metros mais simples e ainda mais incompreendido e pior usado no <strong>mercado da eletroestimula\u00e7\u00e3o global<\/strong>. De <strong>Myox <\/strong>defendemos que o treinamento ideal \u00e9 a soma de: <span style=\"color: #0000ff;\"><strong>PRECIS\u00c3O + SEGURAN\u00c7A + EXIG\u00caNCIA<\/strong>.<\/span>\r\n\r\n&nbsp;\r\n\r\nE isso quer dizer, programamos para alcan\u00e7ar nosso objetivo e se podemos alcan\u00e7\u00e1-los com melhor conforto, ah! Sim, claro, se nosso objetivo for esportivo e a exig\u00eancia de resultados for um sacrif\u00edcio de conforto, pois deve ser assumido. Propomos o seguinte em rela\u00e7\u00e3o \u00e0s rampas:\r\n<ul>\r\n \t<li><strong>ganho de t\u00f4nus \u200b\u200bmuscular em sujeitos n\u00e3o profissionais: 1,5 s de rampa de subida (1,2 rampa de descida)<\/strong><\/li>\r\n \t<li><strong>ganho de for\u00e7a resist\u00eancia ou hipertrofia: 1,2 rampa de subida (0,8 rampa de descida)<\/strong><\/li>\r\n \t<li><strong>ganho de for\u00e7a m\u00e1xima: 0,8 rampa de subida (0,6 rampa de descida)<\/strong><\/li>\r\n \t<li><strong>pot\u00eancia: 0.4 ou 0.5 rampa<\/strong><\/li>\r\n \t<li><strong>potencia em profissionais (boxe, salto, &#8230;): 0 s de rampa, a eliminamos.<\/strong><\/li>\r\n \t<li>Nota 1: a rampa de descida \u00e9 o tempo que a intensidade leva para cair para zero e geralmente \u00e9 um pouco menor que a subida. Uma contra\u00e7\u00e3o \u00e9 a soma de: <strong>RAMPA DE SUBIDA+ MANTENIMENTO DO IMPULSO + RAMPA DE DESCIDA.<\/strong><\/li>\r\n \t<li>Nota 2: <strong>Tudo descrito neste artigo corresponde aos protocolos de Myox advanced training.<\/strong><\/li>\r\n<\/ul>\r\n<img decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/www.myox.fit\/wp-content\/uploads\/2018\/02\/Captura-de-pantalla-2018-02-18-a-las-17.38.08-300x188.jpg\" alt=\"Thais entrenando con easy motion skin, myox.fit\" \/>\r\n\r\n&nbsp;\r\n\r\n<strong style=\"font-size: 23.04px; color: #333333;\">MEU OBJETIVO \u00c9 GLOBAL OU ESPEC\u00cdFICO?<\/strong>\r\n\r\nOk, eu me considero um <strong>personal trainer especialista em eletroestimula\u00e7\u00e3o muscular<\/strong>, por isso devo atender precisamente a minha fun\u00e7\u00e3o principal: <strong>&#8220;personalizar o treinamento com eletroestimula\u00e7\u00e3o muscular&#8221;<\/strong>. Bem, de <strong>Myox EMS<\/strong> n\u00f3s vamos ajud\u00e1-lo em este sentido:\r\n\r\n&nbsp;\r\n\r\nEstudos mostraram que os <strong>ganhos de for\u00e7a com eletroestimula\u00e7\u00e3o<\/strong> s\u00e3o significativamente maiores quando um treinamento \u00e9 realizado de forma local ou anal\u00edtica, comparado a um est\u00edmulo global de uma grande massa muscular. Portanto, a partir da <strong>metodologia Myox EMS<\/strong>, n\u00f3s ensinamos nossos alunos a compreender um <strong>traje de eletroestimula\u00e7\u00e3o<\/strong> n\u00e3o como &#8220;uma unidade ou um todo&#8221;, mas como a soma de muitas unidades, ou seja, a soma de 8, 10 ou 12 circuitos. E \u00e9 que esse modo de entender um <strong>colete de eletroestimula\u00e7\u00e3o muscular<\/strong> sup\u00f5e que o profissional ter\u00e1 a capacidade de tomar uma quantidade e qualidade de decis\u00f5es muito superiores.\r\n\r\nVamos ent\u00e3o, por que te contamos tudo isso? Porque quando nos encontramos com o caso de um cliente que nos diz que sua inten\u00e7\u00e3o \u00e9 fortalecer e levantar os gl\u00fateos o que devemos fazer \u00e9 focar o impulso nesta \u00e1rea, aconselhamos que conecte apenas o circuito que estimula este grupo muscular. O mesmo acontece quando um atleta deseja realizar um treino para o m\u00e1ximo de hipertrofia em seus b\u00edceps. Concentre-se em um \u00fanico grupo muscular antes de estes desafios nos permite aplicar a melhor t\u00e9cnica, controlar os tempos e ritmos, e, claro, a quantidade de intensidade tolerada de forma local ser\u00e1 maior do que se o est\u00edmulo for geral e como eu disse antes nos permitir\u00e1 alcan\u00e7ar os maiores benef\u00edcios.\r\n\r\nPor outro lado, se por raz\u00f5es de tempo, objetivos, ambi\u00e7\u00f5es ou necessidades reais o prop\u00f3sito \u00e9 o ganho de for\u00e7a ou t\u00f4nus geral, podemos trabalhar com os equipamentos conectado. Mesmo assim, desde <strong>Myox<\/strong>, recomendamos aplicar crit\u00e9rios de progress\u00e3o em termos do n\u00famero de m\u00fasculos envolvidos.\r\n\r\n&nbsp;\r\n<h2><strong>QUE EXERC\u00cdCIOS POSSO APLICAR?<\/strong><\/h2>\r\nBem, este \u00e9 um t\u00f3pico muito extenso a ser seguido, ent\u00e3o passo a dar respostas concretas e pr\u00e1ticas e para mais informa\u00e7\u00f5es, aconselho-o a ler mais artigos do nosso blog sobre eletroestimula\u00e7\u00e3o muscular.\r\n\r\n&nbsp;\r\n\r\nGostaria de destacar esses posts:\r\n<ul>\r\n \t<li><a href=\"https:\/\/www.myox.fit\/pt\/bate-papo-hipertrofia-eletroestimulacao\/\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>BATE-PAPO SOBRE HIPOTROFIA COM ELETROESTIMULA\u00c7\u00c3O<\/strong><\/a><\/li>\r\n \t<li><a href=\"https:\/\/www.myox.fit\/pt\/aplicacao-cargas-externas-treinamento-forca-ems\/\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>APLICA\u00c7\u00c3O DE CARGAS EXTERNAS EM TREINAMENTO DE FOR\u00c7A COM ELETROESTIMULA\u00c7\u00c3O MUSCULAR<\/strong><\/a><\/li>\r\n \t<li><strong>PROGRESS\u00c3O NO TREINAMENTO MUSCULA\u00c7\u00c3O + ELETROSTIMULA\u00c7\u00c3O<\/strong><\/li>\r\n \t<li><strong>PAR\u00c2METROS EL\u00c9TRICOS PARA TREINAMENTO DE HIPERTROFIA<\/strong><\/li>\r\n<\/ul>\r\n&nbsp;\r\n\r\nTendo recomendado estas leituras, comentamos:\r\n<ul>\r\n \t<li><strong>Exerc\u00edcios anal\u00edticos<\/strong>, normalmente monoarticulares, quando se toma a decis\u00e3o de realizar treinamento de for\u00e7a em uma \u00e1rea espec\u00edfica, onde todas as exig\u00eancias t\u00e9cnicas e de esfor\u00e7o ser\u00e3o concentradas.<\/li>\r\n \t<li>\u00c9 interessante destacar neste ponto que, em <strong>exerc\u00edcios globais<\/strong>, multiarticulares como o &#8220;agachamento&#8221; ou &#8220;squats&#8221;, pode ser que <strong>a eletroestimula\u00e7\u00e3o provoque a m\u00e1xima implica\u00e7\u00e3o de um dos m\u00fasculos envolvidos neste gesto<\/strong>.<\/li>\r\n \t<li><strong>Exerc\u00edcios globais<\/strong> quando a eletroestimula\u00e7\u00e3o \u00e9 aplicada e modo global, ou seja, todo o traje \u00e9 conectado.<\/li>\r\n<\/ul>\r\n&nbsp;\r\n\r\nGostaria de pontualizar que um dos aspectos mais importantes desenvolvidos em nossas <strong>forma\u00e7\u00f5es Myox<\/strong> \u00e9 aquele que se refere \u00e0 progress\u00e3o, exig\u00eancia e individualiza\u00e7\u00e3o em rela\u00e7\u00e3o \u00e0 combina\u00e7\u00e3o do impulso el\u00e9trico com a\u00e7\u00f5es isom\u00e9tricas. din\u00e2mico-conc\u00eantrico ou din\u00e2mico-exc\u00eantrico. Fique atento ao nosso blog, palestras e forma\u00e7\u00f5es e forneceremos informa\u00e7\u00f5es privilegiadas.\r\n\r\n&nbsp;\r\n\r\nEspero que este artigo tenha ajudado e inspirado voc\u00ea, meu nome \u00e9 <strong>Juan Peris, especialista em eletroestimula\u00e7\u00e3o<\/strong> h\u00e1 quase 20 anos, estou e estarei \u00e0 disposi\u00e7\u00e3o para atender suas d\u00favidas; voc\u00ea pode refletir seus coment\u00e1rios neste blog abaixo ou participar de nossos f\u00f3runs.\r\n\r\n&nbsp;\r\n\r\n&nbsp;\r\n\r\n&nbsp;\r\n<p style=\"text-align: right;\"><a href=\"https:\/\/juanperis.fit\"><em><strong>Juan Peris<\/strong><\/em><\/a><\/p>\r\n<p style=\"text-align: right;\"><a href=\"mailto:juanperis@myox.fit\"><em><strong>juanperis@myox.fit<\/strong><\/em><\/a><\/p>\r\n&nbsp;\r\n<p style=\"text-align: right;\"><strong><em>DEA Ci\u00eancias do Esporte<\/em><\/strong><\/p>\r\n<p style=\"text-align: right;\"><em><strong>Preparador F\u00edsico<\/strong> &#8211; Col. 12.739<\/em><\/p>\r\n<p style=\"text-align: right;\"><em><strong>Fisioterapeuta<\/strong> &#8211; Col. 3.319<\/em><\/p>\r\n<p style=\"text-align: right;\"><a href=\"https:\/\/myox.institute\"><strong><em>Especialista Myox em Eletroestimula\u00e7\u00e3o Muscular<\/em><\/strong><\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>Treinamento de for\u00e7a com trajes ou coletes de eletroestimula\u00e7\u00e3o muscular, que fatores devo considerar? &nbsp; O treinamento com a EMS GLOBAL atrav\u00e9s de trajes ou coletes de eletroestimula\u00e7\u00e3o muscular se espalhou nos \u00faltimos anos em todo o mundo. Mas os treinadores est\u00e3o aplicando com crit\u00e9rios? Existe um conhecimento real de como a eletroestimula\u00e7\u00e3o deve ser [&#8230;]\n","protected":false},"author":11,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-20896","post","type-post","status-publish","format-standard","hentry","category-sin-categorizar"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>TREINAMENTO DE FOR\u00c7A COM COLETE DE ELETROESTIMULA\u00c7\u00c3O MUSCULAR - Myox.fit \u00ae<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/myox.fit\/pt\/treinamento-forca-colete-eletroestimulacao-muscular\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"TREINAMENTO DE FOR\u00c7A COM COLETE DE ELETROESTIMULA\u00c7\u00c3O MUSCULAR - Myox.fit \u00ae\" \/>\n<meta property=\"og:description\" content=\"Treinamento de for\u00e7a com trajes ou coletes de eletroestimula\u00e7\u00e3o muscular, que fatores devo considerar? &nbsp; O treinamento com a EMS GLOBAL atrav\u00e9s de trajes ou coletes de eletroestimula\u00e7\u00e3o muscular se espalhou nos \u00faltimos anos em todo o mundo. Mas os treinadores est\u00e3o aplicando com crit\u00e9rios? Existe um conhecimento real de como a eletroestimula\u00e7\u00e3o deve ser [...]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/myox.fit\/pt\/treinamento-forca-colete-eletroestimulacao-muscular\/\" \/>\n<meta property=\"og:site_name\" content=\"Myox.fit \u00ae\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Myox.fit\/\" \/>\n<meta property=\"article:published_time\" content=\"2018-06-03T22:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-12-23T02:42:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.myox.fit\/wp-content\/uploads\/2018\/05\/Thais-ems-global-fuerza-281x300.jpg\" \/>\n<meta name=\"author\" content=\"Thais de Moura\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Thais de Moura\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/myox.fit\\\/pt\\\/treinamento-forca-colete-eletroestimulacao-muscular\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/myox.fit\\\/pt\\\/treinamento-forca-colete-eletroestimulacao-muscular\\\/\"},\"author\":{\"name\":\"Thais de Moura\",\"@id\":\"https:\\\/\\\/myox.fit\\\/pt\\\/#\\\/schema\\\/person\\\/87ab2ac62007bb2bc63c04dbee045afb\"},\"headline\":\"TREINAMENTO DE FOR\u00c7A COM COLETE DE ELETROESTIMULA\u00c7\u00c3O MUSCULAR\",\"datePublished\":\"2018-06-03T22:00:00+00:00\",\"dateModified\":\"2023-12-23T02:42:14+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/myox.fit\\\/pt\\\/treinamento-forca-colete-eletroestimulacao-muscular\\\/\"},\"wordCount\":1582,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/myox.fit\\\/pt\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/myox.fit\\\/pt\\\/treinamento-forca-colete-eletroestimulacao-muscular\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.myox.fit\\\/wp-content\\\/uploads\\\/2018\\\/05\\\/Thais-ems-global-fuerza-281x300.jpg\",\"articleSection\":[\"Sin categorizar\"],\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/myox.fit\\\/pt\\\/treinamento-forca-colete-eletroestimulacao-muscular\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/myox.fit\\\/pt\\\/treinamento-forca-colete-eletroestimulacao-muscular\\\/\",\"url\":\"https:\\\/\\\/myox.fit\\\/pt\\\/treinamento-forca-colete-eletroestimulacao-muscular\\\/\",\"name\":\"TREINAMENTO DE FOR\u00c7A COM COLETE DE ELETROESTIMULA\u00c7\u00c3O MUSCULAR - Myox.fit \u00ae\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/myox.fit\\\/pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/myox.fit\\\/pt\\\/treinamento-forca-colete-eletroestimulacao-muscular\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/myox.fit\\\/pt\\\/treinamento-forca-colete-eletroestimulacao-muscular\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.myox.fit\\\/wp-content\\\/uploads\\\/2018\\\/05\\\/Thais-ems-global-fuerza-281x300.jpg\",\"datePublished\":\"2018-06-03T22:00:00+00:00\",\"dateModified\":\"2023-12-23T02:42:14+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/myox.fit\\\/pt\\\/treinamento-forca-colete-eletroestimulacao-muscular\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/myox.fit\\\/pt\\\/treinamento-forca-colete-eletroestimulacao-muscular\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/myox.fit\\\/pt\\\/treinamento-forca-colete-eletroestimulacao-muscular\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.myox.fit\\\/wp-content\\\/uploads\\\/2018\\\/05\\\/Thais-ems-global-fuerza-281x300.jpg\",\"contentUrl\":\"https:\\\/\\\/www.myox.fit\\\/wp-content\\\/uploads\\\/2018\\\/05\\\/Thais-ems-global-fuerza-281x300.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/myox.fit\\\/pt\\\/treinamento-forca-colete-eletroestimulacao-muscular\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/myox.fit\\\/pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"TREINAMENTO DE FOR\u00c7A COM COLETE DE ELETROESTIMULA\u00c7\u00c3O MUSCULAR\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/myox.fit\\\/pt\\\/#website\",\"url\":\"https:\\\/\\\/myox.fit\\\/pt\\\/\",\"name\":\"Myox.fit \u00ae\",\"description\":\"Entrenamiento Personal y Fisioterapia en la Nuc\u00eda y online con App Myox | Cursos de electroestimulaci\u00f3n muscular | Tienda online: Compex, Chattanooga, Vitobest,...\",\"publisher\":{\"@id\":\"https:\\\/\\\/myox.fit\\\/pt\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/myox.fit\\\/pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/myox.fit\\\/pt\\\/#organization\",\"name\":\"Myox\",\"url\":\"https:\\\/\\\/myox.fit\\\/pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/myox.fit\\\/pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/myox.fit\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/myox.mediano.png\",\"contentUrl\":\"https:\\\/\\\/myox.fit\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/myox.mediano.png\",\"width\":351,\"height\":118,\"caption\":\"Myox\"},\"image\":{\"@id\":\"https:\\\/\\\/myox.fit\\\/pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Myox.fit\\\/\",\"https:\\\/\\\/www.instagram.com\\\/myox.fit\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/juanperis\\\/\",\"https:\\\/\\\/www.youtube.com\\\/MyoxFit\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/myox.fit\\\/pt\\\/#\\\/schema\\\/person\\\/87ab2ac62007bb2bc63c04dbee045afb\",\"name\":\"Thais de Moura\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a88e4fb2f1a3713d5f46991d4b7ce8519431da1163bc962e06cb62d8f9d35c9d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a88e4fb2f1a3713d5f46991d4b7ce8519431da1163bc962e06cb62d8f9d35c9d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a88e4fb2f1a3713d5f46991d4b7ce8519431da1163bc962e06cb62d8f9d35c9d?s=96&d=mm&r=g\",\"caption\":\"Thais de Moura\"},\"url\":\"https:\\\/\\\/myox.fit\\\/pt\\\/author\\\/thais-de-moura\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"TREINAMENTO DE FOR\u00c7A COM COLETE DE ELETROESTIMULA\u00c7\u00c3O MUSCULAR - Myox.fit \u00ae","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/myox.fit\/pt\/treinamento-forca-colete-eletroestimulacao-muscular\/","og_locale":"pt_PT","og_type":"article","og_title":"TREINAMENTO DE FOR\u00c7A COM COLETE DE ELETROESTIMULA\u00c7\u00c3O MUSCULAR - Myox.fit \u00ae","og_description":"Treinamento de for\u00e7a com trajes ou coletes de eletroestimula\u00e7\u00e3o muscular, que fatores devo considerar? &nbsp; O treinamento com a EMS GLOBAL atrav\u00e9s de trajes ou coletes de eletroestimula\u00e7\u00e3o muscular se espalhou nos \u00faltimos anos em todo o mundo. Mas os treinadores est\u00e3o aplicando com crit\u00e9rios? Existe um conhecimento real de como a eletroestimula\u00e7\u00e3o deve ser [...]","og_url":"https:\/\/myox.fit\/pt\/treinamento-forca-colete-eletroestimulacao-muscular\/","og_site_name":"Myox.fit \u00ae","article_publisher":"https:\/\/www.facebook.com\/Myox.fit\/","article_published_time":"2018-06-03T22:00:00+00:00","article_modified_time":"2023-12-23T02:42:14+00:00","og_image":[{"url":"https:\/\/www.myox.fit\/wp-content\/uploads\/2018\/05\/Thais-ems-global-fuerza-281x300.jpg","type":"","width":"","height":""}],"author":"Thais de Moura","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Thais de Moura","Tempo estimado de leitura":"8 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/myox.fit\/pt\/treinamento-forca-colete-eletroestimulacao-muscular\/#article","isPartOf":{"@id":"https:\/\/myox.fit\/pt\/treinamento-forca-colete-eletroestimulacao-muscular\/"},"author":{"name":"Thais de Moura","@id":"https:\/\/myox.fit\/pt\/#\/schema\/person\/87ab2ac62007bb2bc63c04dbee045afb"},"headline":"TREINAMENTO DE FOR\u00c7A COM COLETE DE ELETROESTIMULA\u00c7\u00c3O MUSCULAR","datePublished":"2018-06-03T22:00:00+00:00","dateModified":"2023-12-23T02:42:14+00:00","mainEntityOfPage":{"@id":"https:\/\/myox.fit\/pt\/treinamento-forca-colete-eletroestimulacao-muscular\/"},"wordCount":1582,"commentCount":0,"publisher":{"@id":"https:\/\/myox.fit\/pt\/#organization"},"image":{"@id":"https:\/\/myox.fit\/pt\/treinamento-forca-colete-eletroestimulacao-muscular\/#primaryimage"},"thumbnailUrl":"https:\/\/www.myox.fit\/wp-content\/uploads\/2018\/05\/Thais-ems-global-fuerza-281x300.jpg","articleSection":["Sin categorizar"],"inLanguage":"pt-PT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/myox.fit\/pt\/treinamento-forca-colete-eletroestimulacao-muscular\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/myox.fit\/pt\/treinamento-forca-colete-eletroestimulacao-muscular\/","url":"https:\/\/myox.fit\/pt\/treinamento-forca-colete-eletroestimulacao-muscular\/","name":"TREINAMENTO DE FOR\u00c7A COM COLETE DE ELETROESTIMULA\u00c7\u00c3O MUSCULAR - Myox.fit \u00ae","isPartOf":{"@id":"https:\/\/myox.fit\/pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/myox.fit\/pt\/treinamento-forca-colete-eletroestimulacao-muscular\/#primaryimage"},"image":{"@id":"https:\/\/myox.fit\/pt\/treinamento-forca-colete-eletroestimulacao-muscular\/#primaryimage"},"thumbnailUrl":"https:\/\/www.myox.fit\/wp-content\/uploads\/2018\/05\/Thais-ems-global-fuerza-281x300.jpg","datePublished":"2018-06-03T22:00:00+00:00","dateModified":"2023-12-23T02:42:14+00:00","breadcrumb":{"@id":"https:\/\/myox.fit\/pt\/treinamento-forca-colete-eletroestimulacao-muscular\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/myox.fit\/pt\/treinamento-forca-colete-eletroestimulacao-muscular\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/myox.fit\/pt\/treinamento-forca-colete-eletroestimulacao-muscular\/#primaryimage","url":"https:\/\/www.myox.fit\/wp-content\/uploads\/2018\/05\/Thais-ems-global-fuerza-281x300.jpg","contentUrl":"https:\/\/www.myox.fit\/wp-content\/uploads\/2018\/05\/Thais-ems-global-fuerza-281x300.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/myox.fit\/pt\/treinamento-forca-colete-eletroestimulacao-muscular\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/myox.fit\/pt\/"},{"@type":"ListItem","position":2,"name":"TREINAMENTO DE FOR\u00c7A COM COLETE DE ELETROESTIMULA\u00c7\u00c3O MUSCULAR"}]},{"@type":"WebSite","@id":"https:\/\/myox.fit\/pt\/#website","url":"https:\/\/myox.fit\/pt\/","name":"Myox.fit \u00ae","description":"Entrenamiento Personal y Fisioterapia en la Nuc\u00eda y online con App Myox | Cursos de electroestimulaci\u00f3n muscular | Tienda online: Compex, Chattanooga, Vitobest,...","publisher":{"@id":"https:\/\/myox.fit\/pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/myox.fit\/pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/myox.fit\/pt\/#organization","name":"Myox","url":"https:\/\/myox.fit\/pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/myox.fit\/pt\/#\/schema\/logo\/image\/","url":"https:\/\/myox.fit\/wp-content\/uploads\/2020\/01\/myox.mediano.png","contentUrl":"https:\/\/myox.fit\/wp-content\/uploads\/2020\/01\/myox.mediano.png","width":351,"height":118,"caption":"Myox"},"image":{"@id":"https:\/\/myox.fit\/pt\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Myox.fit\/","https:\/\/www.instagram.com\/myox.fit\/","https:\/\/www.linkedin.com\/in\/juanperis\/","https:\/\/www.youtube.com\/MyoxFit"]},{"@type":"Person","@id":"https:\/\/myox.fit\/pt\/#\/schema\/person\/87ab2ac62007bb2bc63c04dbee045afb","name":"Thais de Moura","image":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/secure.gravatar.com\/avatar\/a88e4fb2f1a3713d5f46991d4b7ce8519431da1163bc962e06cb62d8f9d35c9d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a88e4fb2f1a3713d5f46991d4b7ce8519431da1163bc962e06cb62d8f9d35c9d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a88e4fb2f1a3713d5f46991d4b7ce8519431da1163bc962e06cb62d8f9d35c9d?s=96&d=mm&r=g","caption":"Thais de Moura"},"url":"https:\/\/myox.fit\/pt\/author\/thais-de-moura\/"}]}},"_links":{"self":[{"href":"https:\/\/myox.fit\/pt\/wp-json\/wp\/v2\/posts\/20896","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/myox.fit\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/myox.fit\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/myox.fit\/pt\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/myox.fit\/pt\/wp-json\/wp\/v2\/comments?post=20896"}],"version-history":[{"count":0,"href":"https:\/\/myox.fit\/pt\/wp-json\/wp\/v2\/posts\/20896\/revisions"}],"wp:attachment":[{"href":"https:\/\/myox.fit\/pt\/wp-json\/wp\/v2\/media?parent=20896"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/myox.fit\/pt\/wp-json\/wp\/v2\/categories?post=20896"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/myox.fit\/pt\/wp-json\/wp\/v2\/tags?post=20896"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}